{"id":2178,"count":1,"description":"","link":"https:\/\/sites.thomsonreuters.com.au\/journals\/tag\/pierre-de-vos\/","name":"Pierre De Vos","slug":"pierre-de-vos","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/sites.thomsonreuters.com.au\/journals\/wp-json\/wp\/v2\/tags\/2178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.thomsonreuters.com.au\/journals\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/sites.thomsonreuters.com.au\/journals\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/sites.thomsonreuters.com.au\/journals\/wp-json\/wp\/v2\/posts?tags=2178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}